{"id":617,"date":"2010-04-02T15:34:52","date_gmt":"2010-04-02T16:34:52","guid":{"rendered":"http:\/\/adolfotomasini.ch\/?p=617"},"modified":"2016-01-13T16:32:31","modified_gmt":"2016-01-13T15:32:31","slug":"qual-e-il-numero-ideale-di-allievi-per-classe","status":"publish","type":"post","link":"https:\/\/adolfotomasini.ch\/wordpress\/qual-e-il-numero-ideale-di-allievi-per-classe\/","title":{"rendered":"Qual \u00e8 il numero ideale di allievi per classe?"},"content":{"rendered":"<p>La scuola ticinese \u00e8 inerte perch\u00e9 ha troppi allievi per classe. La loro riduzione \u00e8 \u00abla misura cardine per permettere una svolta positiva\u00bb contro \u00abl\u2019immobilismo progettuale nel settore della scuola dell\u2019obbligo\u00bb. Lo ha detto la VPOD Docenti, come ha riportato La Regione del 27 marzo, mentre il concetto era gi\u00e0 stato ribadito in precedenza dal segretario della VPOD Raoul Ghisletta, che, in un articolo pubblicato dal foglio bellinzonese (23 marzo), mi aveva messo alla berlina con Diego Erba, poich\u00e9 entrambi saremmo colpevoli di \u00abdormire sugli allori\u00bb e di attuare una politica suicidaria \u00abper la scuola pubblica e soprattutto per la societ\u00e0 ticinese\u00bb. Tuttavia ricondurre l\u2019immobilismo della nostra scuola al numero di allievi per classe \u00e8, a dir poco, un luogo comune un po\u2019 stantio. Per chiarezza: non sono sic et simpliciter contro la riduzione del numero di allievi per classe. Reputo per\u00f2 che una diminuzione lineare e generalizzata sarebbe controproducente e superflua, per diverse ragioni sulle quali mi sono gi\u00e0 chinato. Semmai, ancor prima di chiedere riforme strutturali sui generis, converrebbe esaminare quali sono gli spazi che gi\u00e0 l\u2019attuale legislazione concede, almeno a parole. Vediamo. Le regole in vigore stabiliscono che le monoclassi possono avere da un minimo di 13 a un massimo di 25 allievi, ma indicativamente tra 20 e 25. Aggiungono pure che il dipartimento pu\u00f2 autorizzare o imporre deroghe ai parametri indicati quando le caratteristiche socioculturali degli allievi richiedono un\u2019assistenza particolare. Qui sta semmai la duplice spregiudicatezza del DECS, che ha solitamente come punto di riferimento il massimo degli allievi e che mai ha considerato la necessit\u00e0 di considerare l\u2019importanza delle caratteristiche socioculturali degli allievi, che in nessun caso si ripartiscono equamente in ogni istituto del cantone. L\u2019ho gi\u00e0 scritto in questa rubrica: \u00abl\u2019equit\u00e0 numerica di una classe dipende soprattutto dalle caratteristiche individuali di ogni allievo e dalla natura degli obiettivi che si perseguono. Definire un numero tot di allievi per ogni classe da Airolo a Chiasso a prescindere dalle differenze che sussistono da una sede scolastica all\u2019altra \u00e8 un po\u2019 come decidere che tutti dobbiamo pagare le stesse imposte: cio\u00e8 un\u2019ingiustizia\u00bb (7.10.09).<br \/>\nDi ammuffita, invece, sembra esserci proprio la questione del numero di allievi per classe, che si affaccia alla ribalta a scadenze regolari, bench\u00e9 negli anni esso sia concretamente calato senza portare chiss\u00e0 quali successi sul piano della riuscita scolastica degli allievi pi\u00f9 iellati. Ben altri sarebbero invece i correttivi da invocare per modificare una struttura scolastica immutata sin dal XIX secolo e copiata pari pari dalle prime scuole dei preti: un\u2019aula, un maestro e un gruppo di allievi. La blasonata scuola finlandese, che Ghisletta evoca cos\u00ec spesso, offre ben altre caratteristiche che contribuirebbero a migliorare anche la nostra scuola. Intanto la Finlandia applica per davvero una politica mirata di aiuto alle scuole, a dipendenza delle loro peculiarit\u00e0. Poi, solo per fare qualche esempio, le note fanno la loro prima apparizione dopo la scuola dell\u2019obbligo; la ripetizione di classe non esiste; accanto ad alcune discipline obbligatorie, ogni allievo ha un discreto margine di manovra per scegliere altre materie che completano il suo curricolo; le ore settimanali di lezione sono una ventina a 7 anni e arrivano a 30 con l\u2019accesso al liceo. Ma, soprattutto, si reputa che l\u2019esigenza di un forte richiamo ai valori morali e umanistici non debba ridursi a mera enunciazione legislativa, da sacrificare giorno dopo giorno sull\u2019altare della trasmissione di conoscenze e di competenze mirate all\u2019inserimento nel mondo del lavoro: tutte cose che ho gi\u00e0 scritto in questa rubrica (24.10.08). Per il resto, checch\u00e9 ne dica Ghisletta, se fossi capo della divisione della scuola del DECS avrei ben altre visioni. Ma sono solo un direttore di scuola comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La scuola ticinese \u00e8 inerte perch\u00e9 ha troppi allievi per classe. La loro riduzione \u00e8 \u00abla misura cardine per permettere una svolta positiva\u00bb contro \u00abl\u2019immobilismo progettuale nel settore della scuola dell\u2019obbligo\u00bb. Lo ha detto la VPOD Docenti, come ha riportato La Regione del 27 marzo, mentre il concetto era gi\u00e0 stato ribadito in precedenza dal &hellip; <a href=\"https:\/\/adolfotomasini.ch\/wordpress\/qual-e-il-numero-ideale-di-allievi-per-classe\/\" class=\"more-link\">Continua la lettura di <span class=\"screen-reader-text\">Qual \u00e8 il numero ideale di allievi per classe?<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[25],"class_list":["post-617","post","type-post","status-publish","format-standard","hentry","category-fuori-dallaula","tag-numero-di-allievi-per-classe"],"_links":{"self":[{"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/posts\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=617"}],"version-history":[{"count":0,"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/posts\/617\/revisions"}],"wp:attachment":[{"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adolfotomasini.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}